{"id":14061,"date":"2022-01-07T10:28:23","date_gmt":"2022-01-07T13:28:23","guid":{"rendered":"https:\/\/aeropuertosuruguay.com.uy\/carrasco\/?p=14061"},"modified":"2022-10-27T10:41:03","modified_gmt":"2022-10-27T13:41:03","slug":"ahora-somos-aeropuertos-uruguay","status":"publish","type":"post","link":"https:\/\/aeropuertodecarrasco.com.uy\/en\/ahora-somos-aeropuertos-uruguay\/","title":{"rendered":"Ahora somos Aeropuertos Uruguay"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14061\" class=\"elementor elementor-14061 elementor-12093\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5b0a97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5b0a97\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c459e7\" data-id=\"5c459e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e7a82b elementor-widget elementor-widget-text-editor\" data-id=\"2e7a82b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los aeropuertos son lugares especiales donde despegan sue\u00f1os, inician aventuras y se viven momentos inolvidables que nos hacen crecer. Nosotros tambi\u00e9n crecemos y en 2022 nos convertimos en Aeropuertos Uruguay.<\/p><p>Nuestro tradicional sol ahora representa a cada uno de los aeropuertos que forman parte del Sistema Nacional de Aeropuertos: Carmelo, Durazno, Paysand\u00fa, Melo, Rivera, Salto, Carrasco y Punta del Este.<\/p><p>Este sol es s\u00edmbolo de nuestro compromiso con Uruguay y nos acompa\u00f1a en esta aventura evolucionando hacia un sol moderno, lleno de energ\u00eda y signo de nuevos tiempos y experiencias por vivir.<\/p><p>Aeropuertos Uruguay forma parte del grupo Corporaci\u00f3n Am\u00e9rica Airports, una empresa global que opera 53 aeropuertos en 6 pa\u00edses: Argentina, Uruguay, Brasil, Ecuador, Italia y Armenia.<\/p><p>Desde 2003 estamos comprometidos con Uruguay aplicando nuestra experiencia en la gesti\u00f3n y operaci\u00f3n del Aeropuerto de Carrasco y del Aeropuerto de Punta del Este.<\/p><p>Nuestra misi\u00f3n es brindar a nuestros pasajeros la mejor experiencia de viaje, con est\u00e1ndares de seguridad y calidad del m\u00e1s alto nivel, aplicando innovaci\u00f3n y tecnolog\u00eda, y desarrollando acciones que contribuyan al desarrollo sostenible.<\/p><p>Con Aeropuertos Uruguay llevaremos nuestra visi\u00f3n y calidad de gesti\u00f3n, tambi\u00e9n al desarrollo del nuevo Sistema Nacional de Aeropuerto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddde7ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddde7ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a0bdb6\" data-id=\"4a0bdb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a07f39 elementor-widget elementor-widget-image\" data-id=\"1a07f39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/aeropuertodecarrasco.com.uy\/wp-content\/uploads\/2022\/01\/mapa-aeros-uy_web.jpg?w=1200&#038;ssl=1\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dae04f elementor-widget elementor-widget-spacer\" data-id=\"2dae04f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe12200 elementor-widget elementor-widget-button\" data-id=\"fe12200\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/aeropuertodecarrasco.com.uy\/wp-content\/uploads\/2022\/09\/Enero-2022-Nace-Aeropuertos-Uruguay.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"the7bootstrap- the7-bootstrap-download\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descargar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Crecemos y nos convertimos en Aeropuertos Uruguay. Nuestro tradicional sol ahora representa a cada uno de los aeropuertos que forman parte del Sistema Nacional de Aeropuertos: Carmelo, Durazno, Paysand\u00fa, Melo, Rivera, Salto, Carrasco y Punta del Este.<\/p>\n","protected":false},"author":1,"featured_media":11679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"page_builder":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-14061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/aeropuertodecarrasco.com.uy\/wp-content\/uploads\/2022\/07\/AeropuertoMVD-2.jpg","_links":{"self":[{"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/posts\/14061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/comments?post=14061"}],"version-history":[{"count":2,"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/posts\/14061\/revisions"}],"predecessor-version":[{"id":15586,"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/posts\/14061\/revisions\/15586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/media\/11679"}],"wp:attachment":[{"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/media?parent=14061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/categories?post=14061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeropuertodecarrasco.com.uy\/en\/wp-json\/wp\/v2\/tags?post=14061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}